{"id":2670,"date":"2025-05-03T17:45:00","date_gmt":"2025-05-03T10:45:00","guid":{"rendered":"https:\/\/sataglobal.com.vn\/?post_type=awsm_job_openings&#038;p=2670"},"modified":"2025-08-16T12:11:58","modified_gmt":"2025-08-16T05:11:58","slug":"digital-marketing-intern","status":"publish","type":"awsm_job_openings","link":"https:\/\/sataglobal.com.vn\/en\/jobs\/digital-marketing-intern\/","title":{"rendered":"Digital Marketing Intern"},"content":{"rendered":"<h6 class=\"wp-block-heading\"><strong>Job Description: <\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Participate in implementing Digital Marketing plans in the company&#039;s real projects.<\/li>\n\n\n\n<li>Run ads (Facebook Ads, Tiktok Ads, etc.), responsible for managing fanpage and website content to improve advertising effectiveness.<\/li>\n\n\n\n<li>Receive content, layout, content presentation, image ideas, video ideas, etc. to proactively manage advertising content suitable for each customer segment, suitable for each stage.<\/li>\n\n\n\n<li>Perform tasks as directed and assigned by Leader.<\/li>\n<\/ul>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Request:<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>4th year students or fresh graduates\/College or University graduates in the fields of Economics, Marketing, Digital Marketing, Journalism, Communications, etc.<\/li>\n\n\n\n<li>Responsible, eager to learn, able to withstand work pressure.<\/li>\n\n\n\n<li>Minimum internship period is 3 months, can work longer with higher salary<\/li>\n\n\n\n<li>Have personal laptop for work.<\/li>\n<\/ul>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Benefits:<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Support stamps and internship report data<\/li>\n\n\n\n<li>Allowance: Lunch + Parking + Dinner<\/li>\n\n\n\n<li>Young, dynamic and friendly environment<\/li>\n\n\n\n<li>Free teabreak (tea, coffee, instant noodles...) every day.<\/li>\n\n\n\n<li>Have an Internal Communications department that organizes activities and listens to employee feedback<\/li>\n\n\n\n<li>Participate in Team-building activities, parties, birthdays, and weekly entertainment activities regularly organized by the Company.<\/li>\n\n\n\n<li>Opportunity to be promoted officially after achieving KPI<\/li>\n\n\n\n<li>Other special benefits according to company regulations<\/li>\n<\/ul>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Working time:<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Working time: Monday \u2013 Saturday (from 08:00 to 17:30). 2 Saturdays off per month.<\/li>\n\n\n\n<li>Working location: 255 Binh Loi, Ward 13, Binh Thanh District, HCMC<\/li>\n<\/ul>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Contact information: <\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Email: tuyenthong.sata@gmail.com<\/li>\n<\/ul>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Job Description: Requirements: Benefits: Working Hours: Contact Information:<\/p>","protected":false},"author":1,"template":"","meta":[],"job-categories":[45],"class_list":["post-2670","awsm_job_openings","type-awsm_job_openings","status-publish","hentry","job-categories-internship-fulltime-tp-hcm","job-category-internship","job-type-full-time","job-location-ho-chi-minh-city"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital Marketing Intern - SATA GLOBAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sataglobal.com.vn\/en\/jobs\/digital-marketing-intern\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital Marketing Intern - SATA GLOBAL\" \/>\n<meta property=\"og:description\" content=\"M\u00f4 t\u1ea3 c\u00f4ng vi\u1ec7c: Y\u00eau c\u1ea7u: Quy\u1ec1n l\u1ee3i \u0111\u01b0\u1ee3c h\u01b0\u1edfng: Th\u1eddi gian l\u00e0m vi\u1ec7c: Th\u00f4ng tin li\u00ean h\u1ec7:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sataglobal.com.vn\/en\/jobs\/digital-marketing-intern\/\" \/>\n<meta property=\"og:site_name\" content=\"SATA GLOBAL\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-16T05:11:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/jobs\\\/digital-marketing-intern\\\/\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/jobs\\\/digital-marketing-intern\\\/\",\"name\":\"Digital Marketing Intern - SATA GLOBAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#website\"},\"datePublished\":\"2025-05-03T10:45:00+00:00\",\"dateModified\":\"2025-08-16T05:11:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/jobs\\\/digital-marketing-intern\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sataglobal.com.vn\\\/jobs\\\/digital-marketing-intern\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/jobs\\\/digital-marketing-intern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Trang ch\u1ee7\",\"item\":\"https:\\\/\\\/sataglobal.com.vn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Job Openings\",\"item\":\"https:\\\/\\\/sataglobal.com.vn\\\/jobs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Digital Marketing Intern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#website\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/\",\"name\":\"SATA GLOBAL\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sataglobal.com.vn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#organization\",\"name\":\"SATA GLOBAL\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/SATA-Signature-phien-ban-chinh-scaled.png\",\"contentUrl\":\"https:\\\/\\\/sataglobal.com.vn\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/SATA-Signature-phien-ban-chinh-scaled.png\",\"width\":2560,\"height\":964,\"caption\":\"SATA GLOBAL\"},\"image\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital Marketing Intern - SATA GLOBAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sataglobal.com.vn\/en\/jobs\/digital-marketing-intern\/","og_locale":"en_US","og_type":"article","og_title":"Digital Marketing Intern - SATA GLOBAL","og_description":"M\u00f4 t\u1ea3 c\u00f4ng vi\u1ec7c: Y\u00eau c\u1ea7u: Quy\u1ec1n l\u1ee3i \u0111\u01b0\u1ee3c h\u01b0\u1edfng: Th\u1eddi gian l\u00e0m vi\u1ec7c: Th\u00f4ng tin li\u00ean h\u1ec7:","og_url":"https:\/\/sataglobal.com.vn\/en\/jobs\/digital-marketing-intern\/","og_site_name":"SATA GLOBAL","article_modified_time":"2025-08-16T05:11:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sataglobal.com.vn\/jobs\/digital-marketing-intern\/","url":"https:\/\/sataglobal.com.vn\/jobs\/digital-marketing-intern\/","name":"Digital Marketing Intern - SATA GLOBAL","isPartOf":{"@id":"https:\/\/sataglobal.com.vn\/#website"},"datePublished":"2025-05-03T10:45:00+00:00","dateModified":"2025-08-16T05:11:58+00:00","breadcrumb":{"@id":"https:\/\/sataglobal.com.vn\/jobs\/digital-marketing-intern\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sataglobal.com.vn\/jobs\/digital-marketing-intern\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sataglobal.com.vn\/jobs\/digital-marketing-intern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Trang ch\u1ee7","item":"https:\/\/sataglobal.com.vn\/"},{"@type":"ListItem","position":2,"name":"Job Openings","item":"https:\/\/sataglobal.com.vn\/jobs\/"},{"@type":"ListItem","position":3,"name":"Digital Marketing Intern"}]},{"@type":"WebSite","@id":"https:\/\/sataglobal.com.vn\/#website","url":"https:\/\/sataglobal.com.vn\/","name":"SATA GLOBAL","description":"","publisher":{"@id":"https:\/\/sataglobal.com.vn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sataglobal.com.vn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sataglobal.com.vn\/#organization","name":"SATA GLOBAL","url":"https:\/\/sataglobal.com.vn\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sataglobal.com.vn\/#\/schema\/logo\/image\/","url":"https:\/\/sataglobal.com.vn\/wp-content\/uploads\/2025\/04\/SATA-Signature-phien-ban-chinh-scaled.png","contentUrl":"https:\/\/sataglobal.com.vn\/wp-content\/uploads\/2025\/04\/SATA-Signature-phien-ban-chinh-scaled.png","width":2560,"height":964,"caption":"SATA GLOBAL"},"image":{"@id":"https:\/\/sataglobal.com.vn\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sataglobal.com.vn\/en\/wp-json\/wp\/v2\/awsm_job_openings\/2670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sataglobal.com.vn\/en\/wp-json\/wp\/v2\/awsm_job_openings"}],"about":[{"href":"https:\/\/sataglobal.com.vn\/en\/wp-json\/wp\/v2\/types\/awsm_job_openings"}],"author":[{"embeddable":true,"href":"https:\/\/sataglobal.com.vn\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/sataglobal.com.vn\/en\/wp-json\/wp\/v2\/media?parent=2670"}],"wp:term":[{"taxonomy":"job-categories","embeddable":true,"href":"https:\/\/sataglobal.com.vn\/en\/wp-json\/wp\/v2\/job-categories?post=2670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}