{"id":23,"count":2,"description":"","link":"https:\/\/sataglobal.com.vn\/vi\/tag\/tnxh\/","name":"tnxh","slug":"tnxh","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u01b0u tr\u1eef tnxh - SATA GLOBAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sataglobal.com.vn\/vi\/tag\/tnxh\/\" \/>\n<meta property=\"og:locale\" content=\"vi_VN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u01b0u tr\u1eef tnxh - SATA GLOBAL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sataglobal.com.vn\/vi\/tag\/tnxh\/\" \/>\n<meta property=\"og:site_name\" content=\"SATA GLOBAL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/tag\\\/tnxh\\\/\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/tag\\\/tnxh\\\/\",\"name\":\"L\u01b0u tr\u1eef tnxh - SATA GLOBAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/tag\\\/tnxh\\\/#breadcrumb\"},\"inLanguage\":\"vi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/tag\\\/tnxh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Trang ch\u1ee7\",\"item\":\"https:\\\/\\\/sataglobal.com.vn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tnxh\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#website\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/\",\"name\":\"SATA GLOBAL\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sataglobal.com.vn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"vi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#organization\",\"name\":\"SATA GLOBAL\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"vi\",\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sataglobal.com.vn\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/SATA-Signature-phien-ban-chinh-scaled.png\",\"contentUrl\":\"https:\\\/\\\/sataglobal.com.vn\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/SATA-Signature-phien-ban-chinh-scaled.png\",\"width\":2560,\"height\":964,\"caption\":\"SATA GLOBAL\"},\"image\":{\"@id\":\"https:\\\/\\\/sataglobal.com.vn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u01b0u tr\u1eef tnxh - SATA GLOBAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sataglobal.com.vn\/vi\/tag\/tnxh\/","og_locale":"vi_VN","og_type":"article","og_title":"L\u01b0u tr\u1eef tnxh - SATA GLOBAL","og_url":"https:\/\/sataglobal.com.vn\/vi\/tag\/tnxh\/","og_site_name":"SATA GLOBAL","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sataglobal.com.vn\/tag\/tnxh\/","url":"https:\/\/sataglobal.com.vn\/tag\/tnxh\/","name":"L\u01b0u tr\u1eef tnxh - SATA GLOBAL","isPartOf":{"@id":"https:\/\/sataglobal.com.vn\/#website"},"breadcrumb":{"@id":"https:\/\/sataglobal.com.vn\/tag\/tnxh\/#breadcrumb"},"inLanguage":"vi"},{"@type":"BreadcrumbList","@id":"https:\/\/sataglobal.com.vn\/tag\/tnxh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Trang ch\u1ee7","item":"https:\/\/sataglobal.com.vn\/"},{"@type":"ListItem","position":2,"name":"tnxh"}]},{"@type":"WebSite","@id":"https:\/\/sataglobal.com.vn\/#website","url":"https:\/\/sataglobal.com.vn\/","name":"SATA GLOBAL","description":"","publisher":{"@id":"https:\/\/sataglobal.com.vn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sataglobal.com.vn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"vi"},{"@type":"Organization","@id":"https:\/\/sataglobal.com.vn\/#organization","name":"SATA GLOBAL","url":"https:\/\/sataglobal.com.vn\/","logo":{"@type":"ImageObject","inLanguage":"vi","@id":"https:\/\/sataglobal.com.vn\/#\/schema\/logo\/image\/","url":"https:\/\/sataglobal.com.vn\/wp-content\/uploads\/2025\/04\/SATA-Signature-phien-ban-chinh-scaled.png","contentUrl":"https:\/\/sataglobal.com.vn\/wp-content\/uploads\/2025\/04\/SATA-Signature-phien-ban-chinh-scaled.png","width":2560,"height":964,"caption":"SATA GLOBAL"},"image":{"@id":"https:\/\/sataglobal.com.vn\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sataglobal.com.vn\/vi\/wp-json\/wp\/v2\/tags\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sataglobal.com.vn\/vi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sataglobal.com.vn\/vi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sataglobal.com.vn\/vi\/wp-json\/wp\/v2\/posts?tags=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}